{"id":2569,"date":"2025-05-27T20:35:38","date_gmt":"2025-05-27T12:35:38","guid":{"rendered":"https:\/\/intl-pack.com\/product\/6-5g-pla-cutlery-set-knife-forkspoon-and-spork-white-pla-6-5g\/"},"modified":"2025-05-27T20:39:07","modified_gmt":"2025-05-27T12:39:07","slug":"6-5g-pla-cutlery-set-knife-forkspoon-and-spork-white-pla-6-5g","status":"publish","type":"product","link":"https:\/\/www.intl-pack.com\/es\/65g-pla-cutlery-set-knife-forkspoon-and-spork-white-pla-65g\/","title":{"rendered":"Juego de cubiertos de PLA de 6,5 g: cuchillo, tenedor, cuchara y tenedor blanco PLA de 6,5 g"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<table >\n<tbody>\n<tr style=\"height: 14.4000pt;\">\n<td  style=\"width: 213.0500pt;\">\n<p>N.\u00ba de art\u00edculo:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>PLA-6.5g<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt;\">\n<p>Tipo:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>Cuchillo, tenedor, cuchara, tenedor<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt;\">\n<p>Longitud:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>\u00a0165 mm, 165 mm, 160 mm<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt;\">\n<p>Peso:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>\u00a03,8 g, 3,4 g, 4,4 g<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt;\">\n<p>Material:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>\u00a0EPL<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt;\">\n<p>Colores disponibles:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>Negro, blanco, transparente<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt;\">\n<p>Paquete:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>1000 piezas\/caja<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt;\">\n<p>Uso:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>Utensilios desechables, cubiertos desechables<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt;\">\n<p>Personalizar<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>Desarrollo de moldes, color, empaque.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt;\">\n<p>Muestra:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>Apoyo<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt;\">\n<p>Personalizaci\u00f3n m\u00ednima:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt;\">\n<p>400 cajas de cart\u00f3n<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"featured_media":2571,"template":"","meta":[],"product_brand":[],"product_cat":[24],"product_tag":[],"class_list":{"0":"post-2569","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-disposable-cutlery","8":"first","9":"instock","10":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.intl-pack.com\/es\/wp-json\/wp\/v2\/product\/2569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intl-pack.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.intl-pack.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.intl-pack.com\/es\/wp-json\/wp\/v2\/product\/2569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intl-pack.com\/es\/wp-json\/wp\/v2\/media\/2571"}],"wp:attachment":[{"href":"https:\/\/www.intl-pack.com\/es\/wp-json\/wp\/v2\/media?parent=2569"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.intl-pack.com\/es\/wp-json\/wp\/v2\/product_brand?post=2569"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.intl-pack.com\/es\/wp-json\/wp\/v2\/product_cat?post=2569"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.intl-pack.com\/es\/wp-json\/wp\/v2\/product_tag?post=2569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}