{"id":2589,"date":"2025-05-27T20:42:03","date_gmt":"2025-05-27T12:42:03","guid":{"rendered":"https:\/\/intl-pack.com\/product\/8oz-pet-deli-container-salad-bowls-280ml-117mm-caliberpet-8oz-117\/"},"modified":"2025-05-27T20:42:03","modified_gmt":"2025-05-27T12:42:03","slug":"8oz-pet-deli-container-salad-bowls-280ml-117mm-caliberpet-8oz-117","status":"publish","type":"product","link":"https:\/\/www.intl-pack.com\/ar\/8oz-pet-deli-container-salad-bowls-280ml-117mm-caliberpet-8oz-117\/","title":{"rendered":"\u0623\u0648\u0639\u064a\u0629 \u0633\u0644\u0637\u0629 \u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0633\u0639\u0629 8 \u0623\u0648\u0646\u0635\u0627\u062a\u060c 280 \u0645\u0644\u060c \u0642\u0637\u0631 117 \u0645\u0645\u060c PET-8oz-117"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p style=\"text-align: left; background: #ffffff; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\n<table border=\"1\" style=\"border-collapse: collapse; border: none; text-align: justify; font-family: 'Times New Roman'; font-size: 10pt;\" cellspacing=\"0\">\n<tbody>\n<tr style=\"height: 14.4000pt;\">\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u0631\u0642\u0645 \u0627\u0644\u0635\u0646\u0641:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\"> PET-8oz-117<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u0633\u0639\u0629 \u0627\u0644\u0641\u0627\u0626\u0636:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u00a08 \u0623\u0648\u0646\u0635\u0629\/340 \u0645\u0644<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u0627\u0644\u0642\u0637\u0631 \u0627\u0644\u0639\u0644\u0648\u064a:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u00d8117 \u0645\u0645<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u0648\u0632\u0646:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">12.5g<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u0645\u0627\u062f\u0629:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u062d\u064a\u0648\u0627\u0646 \u0623\u0644\u064a\u0641<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u0639\u062f\u062f \u0627\u0644\u0623\u0644\u0648\u0627\u0646:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">1-6 \u0623\u0644\u0648\u0627\u0646<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u0637\u064e\u0631\u062f:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">500 \u0623\u0648 1000 \u0642\u0637\u0639\u0629\/\u0643\u0631\u062a\u0648\u0646<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u0634\u0631\u0628 \u0628\u0627\u0631\u062f<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u0627\u0644\u062d\u062f \u0627\u0644\u0623\u062f\u0646\u0649 \u0644\u0643\u0645\u064a\u0629 \u0627\u0644\u0637\u0644\u0628:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">10000 \u0642\u0637\u0639\u0629 \u0645\u0639 \u0637\u0628\u0627\u0639\u0629 \u0627\u0644\u0634\u0639\u0627\u0631<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p class=\"15\" style=\"text-indent: 0.0000pt;\">\u062f\u0631\u062c\u0629 \u0627\u0644\u062d\u0631\u0627\u0631\u0629 \u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0629:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">-20-65 \u062f\u0631\u062c\u0629 \u0645\u0626\u0648\u064a\u0629<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p class=\"15\" style=\"text-indent: 0.0000pt;\">\u0639\u064a\u0646\u0629:<\/p>\n<\/td>\n<td  style=\"width: 213.0500pt; padding: 0.0000pt 5.4000pt 0.0000pt 5.4000pt; border-left: 1.0000pt solid windowtext; border-right: 1.0000pt solid windowtext; border-top: none; border-bottom: 1.0000pt solid windowtext;\">\n<p style=\"text-align: left; margin: 0pt 0pt 0.0001pt; font-family: Calibri; font-size: 10.5pt;\">\u064a\u062f\u0639\u0645<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"featured_media":2591,"template":"","meta":[],"product_brand":[],"product_cat":[28,23],"product_tag":[],"class_list":{"0":"post-2589","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-deli-container","7":"product_cat-catering-packaging","9":"first","10":"instock","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.intl-pack.com\/ar\/wp-json\/wp\/v2\/product\/2589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intl-pack.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.intl-pack.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.intl-pack.com\/ar\/wp-json\/wp\/v2\/product\/2589\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intl-pack.com\/ar\/wp-json\/wp\/v2\/media\/2591"}],"wp:attachment":[{"href":"https:\/\/www.intl-pack.com\/ar\/wp-json\/wp\/v2\/media?parent=2589"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.intl-pack.com\/ar\/wp-json\/wp\/v2\/product_brand?post=2589"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.intl-pack.com\/ar\/wp-json\/wp\/v2\/product_cat?post=2589"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.intl-pack.com\/ar\/wp-json\/wp\/v2\/product_tag?post=2589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}